{"id":709,"date":"2024-05-14T08:07:15","date_gmt":"2024-05-14T06:07:15","guid":{"rendered":"https:\/\/www.ukbb.ch\/?post_type=aufenthalt&#038;p=709"},"modified":"2026-09-01T08:28:56","modified_gmt":"2026-09-01T06:28:56","slug":"unita-di-terapia-intensiva-neonatale","status":"publish","type":"aufenthalt","link":"https:\/\/www.ukbb.ch\/it\/aufenthalt\/neonatologische-intensivstation\/","title":{"rendered":"Unit\u00e0 di terapia intensiva neonatale"},"excerpt":{"rendered":"<p>L'Unit\u00e0 di Terapia Intensiva Neonatale dell'Ospedale Pediatrico Universitario di Basilea (UKBB) offre assistenza e cure complete ai neonati prematuri e malati. Ogni anno vengono ricoverati circa 600 neonati. Le richieste provengono dalla Clinica femminile, dagli ospedali circostanti e da medici privati della Svizzera nordoccidentale e delle vicine Germania e Francia.<\/p>","protected":false},"featured_media":21101,"parent":0,"menu_order":0,"template":"","class_list":["post-709","aufenthalt","type-aufenthalt","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.ukbb.ch\/it\/wp-json\/wp\/v2\/aufenthalt\/709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ukbb.ch\/it\/wp-json\/wp\/v2\/aufenthalt"}],"about":[{"href":"https:\/\/www.ukbb.ch\/it\/wp-json\/wp\/v2\/types\/aufenthalt"}],"version-history":[{"count":2,"href":"https:\/\/www.ukbb.ch\/it\/wp-json\/wp\/v2\/aufenthalt\/709\/revisions"}],"predecessor-version":[{"id":37128,"href":"https:\/\/www.ukbb.ch\/it\/wp-json\/wp\/v2\/aufenthalt\/709\/revisions\/37128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ukbb.ch\/it\/wp-json\/wp\/v2\/media\/21101"}],"wp:attachment":[{"href":"https:\/\/www.ukbb.ch\/it\/wp-json\/wp\/v2\/media?parent=709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}